{"id":165,"count":2,"description":"","link":"https:\/\/comfyevents.ee\/fi\/category\/telgi-paigaldus\/","name":"Telgi paigaldus","slug":"telgi-paigaldus","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Telgi paigaldus - Comfy Events purjetelk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comfyevents.ee\/fi\/category\/telgi-paigaldus\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Telgi paigaldus - Comfy Events purjetelk\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comfyevents.ee\/fi\/category\/telgi-paigaldus\/\" \/>\n<meta property=\"og:site_name\" content=\"Comfy Events purjetelk\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comfyevents.ee\/wp-content\/uploads\/2025\/03\/310158884_527218436080293_8680189412409634702_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/category\\\/telgi-paigaldus\\\/\",\"url\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/category\\\/telgi-paigaldus\\\/\",\"name\":\"Telgi paigaldus - Comfy Events purjetelk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/category\\\/telgi-paigaldus\\\/#breadcrumb\"},\"inLanguage\":\"fi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/category\\\/telgi-paigaldus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/tervetuloa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Telgi paigaldus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/#website\",\"url\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/\",\"name\":\"Comfy Events \u2013 disain peotelgi rent\",\"description\":\"Telgi rent, telkide rent, peotelgi rent, peotelkide rent, pulmatelk, pulmatelgi rent, pulmatelgid, telgipulm, telkide rentimine, peotelkide rentimine\",\"publisher\":{\"@id\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/#organization\",\"name\":\"Comfy Events\",\"url\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comfyevents.ee\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Untitled-design-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comfyevents.ee\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Untitled-design-1.jpg\",\"width\":720,\"height\":720,\"caption\":\"Comfy Events\"},\"image\":{\"@id\":\"https:\\\/\\\/comfyevents.ee\\\/fi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/purjetelk\\\/\",\"http:\\\/\\\/instagram.com\\\/purjetelk\",\"https:\\\/\\\/www.youtube.com\\\/@purjetelk\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Telgi paigaldus - Comfy Events purjetelk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comfyevents.ee\/fi\/category\/telgi-paigaldus\/","og_locale":"fi_FI","og_type":"article","og_title":"Telgi paigaldus - Comfy Events purjetelk","og_url":"https:\/\/comfyevents.ee\/fi\/category\/telgi-paigaldus\/","og_site_name":"Comfy Events purjetelk","og_image":[{"width":2048,"height":1365,"url":"https:\/\/comfyevents.ee\/wp-content\/uploads\/2025\/03\/310158884_527218436080293_8680189412409634702_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/comfyevents.ee\/fi\/category\/telgi-paigaldus\/","url":"https:\/\/comfyevents.ee\/fi\/category\/telgi-paigaldus\/","name":"Telgi paigaldus - Comfy Events purjetelk","isPartOf":{"@id":"https:\/\/comfyevents.ee\/fi\/#website"},"breadcrumb":{"@id":"https:\/\/comfyevents.ee\/fi\/category\/telgi-paigaldus\/#breadcrumb"},"inLanguage":"fi"},{"@type":"BreadcrumbList","@id":"https:\/\/comfyevents.ee\/fi\/category\/telgi-paigaldus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comfyevents.ee\/fi\/tervetuloa\/"},{"@type":"ListItem","position":2,"name":"Telgi paigaldus"}]},{"@type":"WebSite","@id":"https:\/\/comfyevents.ee\/fi\/#website","url":"https:\/\/comfyevents.ee\/fi\/","name":"Comfy Events \u2013 disain peotelgi rent","description":"Telgi rent, telkide rent, peotelgi rent, peotelkide rent, pulmatelk, pulmatelgi rent, pulmatelgid, telgipulm, telkide rentimine, peotelkide rentimine","publisher":{"@id":"https:\/\/comfyevents.ee\/fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comfyevents.ee\/fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/comfyevents.ee\/fi\/#organization","name":"Comfy Events","url":"https:\/\/comfyevents.ee\/fi\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/comfyevents.ee\/fi\/#\/schema\/logo\/image\/","url":"https:\/\/comfyevents.ee\/wp-content\/uploads\/2025\/04\/Untitled-design-1.jpg","contentUrl":"https:\/\/comfyevents.ee\/wp-content\/uploads\/2025\/04\/Untitled-design-1.jpg","width":720,"height":720,"caption":"Comfy Events"},"image":{"@id":"https:\/\/comfyevents.ee\/fi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/purjetelk\/","http:\/\/instagram.com\/purjetelk","https:\/\/www.youtube.com\/@purjetelk"]}]}},"_links":{"self":[{"href":"https:\/\/comfyevents.ee\/fi\/wp-json\/wp\/v2\/categories\/165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comfyevents.ee\/fi\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/comfyevents.ee\/fi\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/comfyevents.ee\/fi\/wp-json\/wp\/v2\/posts?categories=165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}